{"id":7914,"date":"2023-05-16T23:34:28","date_gmt":"2023-05-16T23:34:28","guid":{"rendered":"https://honeybee.ca/ranghinatore-a-nastro-per-cereali-ws/"},"modified":"2024-10-28T19:08:55","modified_gmt":"2024-10-28T19:08:55","slug":"ranghinatore-a-nastro-per-cereali-ws","status":"publish","type":"page","link":"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/","title":{"rendered":"Ranghinatore a nastro per cereali WS"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":588,"featured_media":0,"parent":7923,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-7914","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https://yoast.com/wordpress/plugins/seo/ -->\n<title>Ranghinatore a nastro per cereali WS - Honey Bee Manufacturing</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/\" />\n<meta property=\"og:locale\" content=\"it_IT\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"Ranghinatore a nastro per cereali WS - Honey Bee Manufacturing\" />\n<meta property=\"og:url\" content=\"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/\" />\n<meta property=\"og:site_name\" content=\"Honey Bee Manufacturing\" />\n<meta property=\"article:modified_time\" content=\"2024-10-28T19:08:55+00:00\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" />\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https://schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/\",\"url\":\"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/\",\"name\":\"Ranghinatore a nastro per cereali WS - Honey Bee Manufacturing\",\"isPartOf\":{\"@id\":\"https://staging.honeybee.ca/it/#website\"},\"datePublished\":\"2023-05-16T23:34:28+00:00\",\"dateModified\":\"2024-10-28T19:08:55+00:00\",\"breadcrumb\":{\"@id\":\"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https://staging.honeybee.ca/it/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https://staging.honeybee.ca/it/prodotti/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ranghinatore a nastro per cereali WS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https://staging.honeybee.ca/it/#website\",\"url\":\"https://staging.honeybee.ca/it/\",\"name\":\"Honey Bee Manufacturing\",\"description\":\"Harvest Faster - See our new AirFLEX NXT!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https://staging.honeybee.ca/it/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}</script>\n<!-- / Yoast SEO plugin. -->","yoast_head_json":{"title":"Ranghinatore a nastro per cereali WS - Honey Bee Manufacturing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/","og_locale":"it_IT","og_type":"article","og_title":"Ranghinatore a nastro per cereali WS - Honey Bee Manufacturing","og_url":"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/","og_site_name":"Honey Bee Manufacturing","article_modified_time":"2024-10-28T19:08:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"WebPage","@id":"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/","url":"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/","name":"Ranghinatore a nastro per cereali WS - Honey Bee Manufacturing","isPartOf":{"@id":"https://staging.honeybee.ca/it/#website"},"datePublished":"2023-05-16T23:34:28+00:00","dateModified":"2024-10-28T19:08:55+00:00","breadcrumb":{"@id":"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/"]}]},{"@type":"BreadcrumbList","@id":"https://staging.honeybee.ca/it/prodotti/ranghinatore-a-nastro-per-cereali-ws/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https://staging.honeybee.ca/it/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https://staging.honeybee.ca/it/prodotti/"},{"@type":"ListItem","position":3,"name":"Ranghinatore a nastro per cereali WS"}]},{"@type":"WebSite","@id":"https://staging.honeybee.ca/it/#website","url":"https://staging.honeybee.ca/it/","name":"Honey Bee Manufacturing","description":"Harvest Faster - See our new AirFLEX NXT!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://staging.honeybee.ca/it/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:04:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https://staging.honeybee.ca/it/wp-json/wp/v2/pages/7914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://staging.honeybee.ca/it/wp-json/wp/v2/pages"}],"about":[{"href":"https://staging.honeybee.ca/it/wp-json/wp/v2/types/page"}],"author":[{"embeddable":true,"href":"https://staging.honeybee.ca/it/wp-json/wp/v2/users/588"}],"replies":[{"embeddable":true,"href":"https://staging.honeybee.ca/it/wp-json/wp/v2/comments?post=7914"}],"version-history":[{"count":2,"href":"https://staging.honeybee.ca/it/wp-json/wp/v2/pages/7914/revisions"}],"predecessor-version":[{"id":11297,"href":"https://staging.honeybee.ca/it/wp-json/wp/v2/pages/7914/revisions/11297"}],"up":[{"embeddable":true,"href":"https://staging.honeybee.ca/it/wp-json/wp/v2/pages/7923"}],"wp:attachment":[{"href":"https://staging.honeybee.ca/it/wp-json/wp/v2/media?parent=7914"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}